{"id":999,"date":"2022-01-10T17:15:44","date_gmt":"2022-01-10T10:15:44","guid":{"rendered":"https:\/\/www.yinyangclinic.com\/eng\/?p=999"},"modified":"2022-01-10T17:16:48","modified_gmt":"2022-01-10T10:16:48","slug":"%e0%b8%a1%e0%b8%b5%e0%b8%a5%e0%b8%b9%e0%b8%81%e0%b8%a2%e0%b8%b2%e0%b8%81-%e0%b8%aa%e0%b8%b2%e0%b9%80%e0%b8%ab%e0%b8%95%e0%b8%b8%e0%b8%a1%e0%b8%b2%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%88%e0%b8%b2%e0%b8%81","status":"publish","type":"post","link":"https:\/\/www.yinyangclinic.com\/eng\/%e0%b8%a1%e0%b8%b5%e0%b8%a5%e0%b8%b9%e0%b8%81%e0%b8%a2%e0%b8%b2%e0%b8%81-%e0%b8%aa%e0%b8%b2%e0%b9%80%e0%b8%ab%e0%b8%95%e0%b8%b8%e0%b8%a1%e0%b8%b2%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%88%e0%b8%b2%e0%b8%81\/","title":{"rendered":"\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e21\u0e32\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07"},"content":{"rendered":"<div class=\"gb-container gb-container-ed2a6fbf\"><div class=\"gb-inside-container\">\n\n<h1><strong>\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e21\u0e32\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07<\/strong><\/h1>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-53924b91\"><div class=\"gb-inside-container\">\n\n<blockquote class=\"wp-block-quote\"><p>Welcome to the world \u0e19\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e23\u0e23\u0e13 \u0e15\u0e32\u0e2a\u0e2d\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e31\u0e49\u0e19\u0e0a\u0e48\u0e32\u0e07\u0e19\u0e48\u0e32\u0e2d\u0e34\u0e08\u0e09\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01\u0e04\u0e23\u0e31\u0e1a \u0e2a\u0e27\u0e22\u0e1a\u0e32\u0e14\u0e44\u0e1b\u0e44\u0e2b\u0e19\u0e25\u0e39\u0e01\u00a0<img decoding=\"async\" alt=\"\ud83d\ude06\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f606.svg\" style=\"width: 25px;\"><\/p><\/blockquote>\n\n\n\n<p>\u0e04\u0e19\u0e44\u0e02\u0e49\u0e2d\u0e32\u0e22\u0e38 35 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e39\u0e48\u0e04\u0e23\u0e31\u0e1a \u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e21\u0e32 7 \u0e1b\u0e35\u0e41\u0e25\u0e49\u0e27\u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e40\u0e25\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e25\u0e2d\u0e07\u0e09\u0e35\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e1b 2 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\n\n\n\n<p>\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e25\u0e2d\u0e07\u0e17\u0e33<strong><a href=\"https:\/\/www.yinyangclinic.com\/eng\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b9%82%e0%b8%99%e0%b9%82%e0%b8%a5%e0%b8%a2%e0%b8%b5%e0%b9%80%e0%b8%88%e0%b8%a3%e0%b8%b4%e0%b8%8d%e0%b8%9e%e0%b8%b1%e0%b8%99%e0%b8%98%e0%b9%8c%e0%b8%b8-iui-ivf-icsi\/\" data-type=\"page\" data-id=\"744\">\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27<\/a><\/strong> \u0e09\u0e35\u0e14\u0e22\u0e32\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e44\u0e02\u0e48\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e02\u0e48\u0e21\u0e32\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07 6 \u0e43\u0e1a\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u00a0<img decoding=\"async\" alt=\"\u2757\ufe0f\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/2757.svg\" style=\"width: 25px;\">\u00a0(\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22\u0e16\u0e49\u0e32\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e22\u0e38 \u0e40\u0e04\u0e2a\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e15\u0e23\u0e27\u0e08\u0e27\u0e48\u0e32\u0e04\u0e48\u0e32 AMH \u0e40\u0e17\u0e48\u0e32\u0e44\u0e2b\u0e23\u0e48 \u0e41\u0e15\u0e48\u0e19\u0e48\u0e32\u0e08\u0e30\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32\u0e1b\u0e01\u0e15\u0e34\u0e2d\u0e22\u0e39\u0e48) \u0e41\u0e16\u0e21\u0e1e\u0e2d\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e44\u0e1b\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e21\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e42\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07 3 \u0e15\u0e31\u0e27\u00a0<img decoding=\"async\" alt=\"\u203c\ufe0f\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/203c.svg\" style=\"width: 25px;\">\u00a0\u0e01\u0e47\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e44\u0e27\u0e49 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1c\u0e19\u0e31\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01\u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e22\u0e49\u0e32\u0e22\u0e23\u0e2d\u0e1a\u0e41\u0e0a\u0e48\u0e41\u0e02\u0e47\u0e07<\/p>\n\n\n\n<p>\u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e25\u0e30\u0e25\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 1 \u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\u00a0<img decoding=\"async\" alt=\"\u203c\ufe0f\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/203c.svg\" style=\"width: 25px;\"><img decoding=\"async\" alt=\"\ud83d\ude16\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f616.svg\" style=\"width: 25px;\">\u00a0\u0e22\u0e49\u0e32\u0e22\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e15\u0e34\u0e14 \u0e19\u0e36\u0e01\u0e20\u0e32\u0e1e\u0e40\u0e07\u0e34\u0e19\u0e41\u0e2a\u0e19\u0e42\u0e1a\u0e22\u0e1a\u0e34\u0e19\u0e44\u0e1b\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a\u00a0<img decoding=\"async\" alt=\"\ud83d\udcb8\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f4b8.svg\" style=\"width: 25px;\">\u00a0<img decoding=\"async\" alt=\"\ud83d\udcb8\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f4b8.svg\" style=\"width: 25px;\"><\/p>\n\n\n\n<p>\u0e15\u0e23\u0e27\u0e08\u0e21\u0e32\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e15\u0e31\u0e19 \u0e21\u0e14\u0e25\u0e39\u0e01\u0e2a\u0e30\u0e2d\u0e32\u0e14 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e0b\u0e35\u0e2a\u0e15\u0e4c \u0e44\u0e21\u0e48\u0e21\u0e35\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e07\u0e2d\u0e01 \u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e40\u0e1e\u0e28\u0e01\u0e47\u0e1b\u0e01\u0e15\u0e34<\/p>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e0a\u0e32\u0e22\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e44\u0e1b\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 14 \u0e25\u0e49\u0e32\u0e19\u0e15\u0e31\u0e27 \u0e21\u0e35\u0e40\u0e2a\u0e49\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e02\u0e2d\u0e14\u0e17\u0e35\u0e48\u0e2d\u0e31\u0e13\u0e11\u0e30\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e23\u0e38\u0e19\u0e41\u0e23\u0e07\u0e16\u0e36\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a 3 (\u0e17\u0e23\u0e32\u0e1a\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e44\u0e2b\u0e19 \u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e21\u0e37\u0e2d\u0e2b\u0e21\u0e2d\u0e04\u0e25\u0e33\u0e04\u0e23\u0e31\u0e1a\u00a0<img decoding=\"async\" alt=\"\ud83d\ude02\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f602.svg\" style=\"width: 25px;\">)<\/p>\n\n\n\n<p>\u0e40\u0e25\u0e22\u0e23\u0e31\u0e01\u0e29\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e04\u0e19\u0e04\u0e23\u0e31\u0e1a<\/p>\n\n\n\n<p>\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e19\u0e31\u0e49\u0e19\u0e0a\u0e35\u0e1e\u0e08\u0e23\u0e41\u0e1c\u0e48\u0e27\u0e40\u0e1a\u0e32 \u0e40\u0e25\u0e37\u0e2d\u0e14\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e40\u0e25\u0e22 \u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e22\u0e32\u0e21\u0e15\u0e23\u0e27\u0e08\u0e14\u0e39\u0e25\u0e34\u0e49\u0e19\u0e01\u0e47\u0e04\u0e25\u0e49\u0e33\u0e41\u0e14\u0e07 \u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e21\u0e35\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e04\u0e31\u0e48\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e2d\u0e1a\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d 30-40 \u0e27\u0e31\u0e19\u0e21\u0e32\u0e04\u0e23\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e08\u0e36\u0e07\u0e40\u0e19\u0e49\u0e19\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e14 \u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25\u0e40\u0e27\u0e35\u0e22\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e15\u0e23\u0e07\u0e23\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e2d\u0e19\u0e43\u0e2b\u0e49\u0e2b\u0e32\u0e27\u0e31\u0e19\u0e44\u0e02\u0e48\u0e15\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e25\u0e2d\u0e07\u0e22\u0e38\u0e48\u0e07\u0e01\u0e31\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e1b\u0e1e\u0e25\u0e32\u0e07 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e44\u0e1b\u0e1e\u0e25\u0e32\u0e07<\/p>\n\n\n\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22\u0e19\u0e31\u0e49\u0e19\u0e21\u0e31\u0e01\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e19\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e14\u0e35 \u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e1b\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1c\u0e25\u0e07\u0e48\u0e32\u0e22 \u0e14\u0e27\u0e07\u0e15\u0e32\u0e21\u0e31\u0e01\u0e41\u0e14\u0e07 \u0e15\u0e23\u0e27\u0e08\u0e14\u0e39\u0e25\u0e34\u0e49\u0e19\u0e1e\u0e1a\u0e27\u0e48\u0e32\u0e41\u0e14\u0e07 \u0e2d\u0e32\u0e01\u0e32\u0e23\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e08\u0e31\u0e14\u0e44\u0e1b\u0e17\u0e32\u0e07 \u201c\u0e23\u0e49\u0e2d\u0e19\u201d\u00a0<img decoding=\"async\" alt=\"\ud83d\udd25\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f525.svg\" style=\"width: 25px;\">\u0e40\u0e01\u0e34\u0e19\u0e04\u0e23\u0e31\u0e1a \u0e01\u0e47\u0e40\u0e25\u0e22\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e18\u0e32\u0e15\u0e38\u0e43\u0e2b\u0e49\u0e0a\u0e38\u0e48\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e1a\u0e33\u0e23\u0e38\u0e07\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25\u0e40\u0e27\u0e35\u0e22\u0e19\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e2d\u0e31\u0e13\u0e11\u0e30 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e2b\u0e25\u0e31\u0e1a\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e04\u0e48\u0e2d\u0e22\u0e23\u0e49\u0e2d\u0e19\u0e43\u0e19\u0e41\u0e25\u0e49\u0e27<\/p>\n\n\n\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e40\u0e02\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e17\u0e32\u0e07\u0e17\u0e31\u0e49\u0e07\u0e04\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e19\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e23\u0e23\u0e13\u0e01\u0e47\u0e21\u0e32\u0e40\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e1a\u00a0<img decoding=\"async\" alt=\"\ud83e\udd30\ud83c\udffc\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f930-1f3fc.svg\" style=\"width: 25px;\"><\/p>\n\n\n\n<p>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30<strong><a href=\"https:\/\/www.yinyangclinic.com\/eng\/how-to-make-a-baby\/\" data-type=\"page\" data-id=\"140\">\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01<\/a><\/strong> \u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e2d\u0e31\u0e15\u0e23\u0e32\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e04\u0e23\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e32\u0e27 \u0e46 20-30% \u0e41\u0e25\u0e30\u0e44\u0e14\u0e49\u0e22\u0e34\u0e19\u0e27\u0e48\u0e32\u0e2a\u0e39\u0e07\u0e16\u0e36\u0e0750-60%\u0e43\u0e19\u0e1a\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e40\u0e25\u0e22 \u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32\u0e2b\u0e32\u0e01\u0e1e\u0e25\u0e32\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e41\u0e25\u0e49\u0e27 \u0e0a\u0e35\u0e27\u0e34\u0e15\u0e19\u0e35\u0e49\u0e08\u0e30\u0e2b\u0e21\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e31\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e25\u0e39\u0e01\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22 \u0e46 \u0e40\u0e04\u0e2a\u0e17\u0e35\u0e48\u0e1e\u0e25\u0e32\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e22\u0e31\u0e07\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e1a \u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<p>\u0e43\u0e19\u0e17\u0e32\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e01\u0e31\u0e19 \u0e01\u0e32\u0e23\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e44\u0e1b\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e01\u0e47\u0e08\u0e30\u0e22\u0e34\u0e48\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49 \u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e19\u0e01\u0e33\u0e40\u0e07\u0e34\u0e19\u0e44\u0e1b\u0e2b\u0e32\u0e2b\u0e21\u0e2d\u0e17\u0e37\u0e48\u0e2d \u0e46 \u0e44\u0e21\u0e48\u0e07\u0e31\u0e49\u0e19\u0e40\u0e14\u0e35\u0e4b\u0e22\u0e27\u0e40\u0e07\u0e34\u0e19\u0e1b\u0e25\u0e34\u0e27\u0e2d\u0e35\u0e01\u00a0<img decoding=\"async\" alt=\"\ud83d\udcb8\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f4b8.svg\" style=\"width: 25px;\"><\/p>\n\n<\/div><\/div>\n\n\n<p>\u0e17\u0e33\u0e19\u0e31\u0e14\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp;<a href=\"tel:0947946006\">094-794-6006<\/a><\/p>\n\n\n\n<p>\u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e02\u0e49\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21 Facebook \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp;<a href=\"https:\/\/www.facebook.com\/chenyinyangclinic\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/www.facebook.com\/chenyinyangclinic<\/strong><\/a><\/p>\n\n\n\n<p>\u0e2b\u0e22\u0e34\u0e19\u0e2b\u0e22\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 999\/1-2 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e41\u0e02\u0e27\u0e07\u0e04\u0e25\u0e2d\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e40\u0e02\u0e15\u0e1a\u0e36\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e 10230<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e21\u0e32\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07 Welcome to the world \u0e19\u0e49\u0e2d\u0e07\u0e27\u0e34\u0e27\u0e23\u0e23\u0e13 \u0e15\u0e32\u0e2a\u0e2d\u0e07\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e31\u0e49\u0e19 &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e21\u0e32\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07\" class=\"read-more button\" href=\"https:\/\/www.yinyangclinic.com\/eng\/%e0%b8%a1%e0%b8%b5%e0%b8%a5%e0%b8%b9%e0%b8%81%e0%b8%a2%e0%b8%b2%e0%b8%81-%e0%b8%aa%e0%b8%b2%e0%b9%80%e0%b8%ab%e0%b8%95%e0%b8%b8%e0%b8%a1%e0%b8%b2%e0%b9%84%e0%b8%94%e0%b9%89%e0%b8%88%e0%b8%b2%e0%b8%81\/#more-999\" aria-label=\"More on \u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01 \u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e21\u0e32\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e0a\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07\">Read More &gt;&gt;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,8,20,9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/999"}],"collection":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/comments?post=999"}],"version-history":[{"count":0,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media\/1001"}],"wp:attachment":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media?parent=999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/categories?post=999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/tags?post=999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}