{"id":994,"date":"2022-01-10T17:06:08","date_gmt":"2022-01-10T10:06:08","guid":{"rendered":"https:\/\/www.yinyangclinic.com\/eng\/?p=994"},"modified":"2022-01-10T17:06:29","modified_gmt":"2022-01-10T10:06:29","slug":"%e0%b8%97%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%b3%e0%b9%84%e0%b8%82%e0%b9%88%e0%b8%95%e0%b8%b1%e0%b8%99-%e0%b9%82%e0%b8%ad%e0%b8%81%e0%b8%b2%e0%b8%aa%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%80%e0%b8%9b%e0%b8%b4","status":"publish","type":"post","link":"https:\/\/www.yinyangclinic.com\/eng\/%e0%b8%97%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%b3%e0%b9%84%e0%b8%82%e0%b9%88%e0%b8%95%e0%b8%b1%e0%b8%99-%e0%b9%82%e0%b8%ad%e0%b8%81%e0%b8%b2%e0%b8%aa%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%80%e0%b8%9b%e0%b8%b4\/","title":{"rendered":"\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19"},"content":{"rendered":"<div class=\"gb-container gb-container-25b2ac16\"><div class=\"gb-inside-container\">\n\n<h1><strong>\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19<\/strong><\/h1>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-be42f720\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-471d699b\"><div class=\"gb-inside-container\">\n\n<h2><strong>\u0e04\u0e19\u0e44\u0e02\u0e49\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19\u0e2a\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e07\u0e1e\u0e36\u0e48\u0e07\u0e41\u0e08\u0e49\u0e07\u0e02\u0e48\u0e32\u0e27\u0e14\u0e35\u0e21\u0e32\u0e04\u0e23\u0e31\u0e1a \u0e22\u0e34\u0e19\u0e14\u0e35\u0e21\u0e32\u0e01<\/strong><\/h2>\n\n<\/div><\/div>\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-cf09480e\"><div class=\"gb-inside-container\">\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"640\" height=\"960\" src=\"https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2022\/01\/\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19-\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19-1.jpg\" alt=\"\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\" class=\"wp-image-995\" srcset=\"https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2022\/01\/\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19-\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19-1.jpg 640w, https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2022\/01\/\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19-\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19-1-200x300.jpg 200w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-b47963de\"><div class=\"gb-inside-container\">\n\n<p>\u0e1b\u0e01\u0e15\u0e34\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2b\u0e25\u0e31\u0e01\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30<strong><a href=\"https:\/\/www.yinyangclinic.com\/eng\/how-to-make-a-baby\/\" data-type=\"page\" data-id=\"140\">\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01<\/a><\/strong>\u0e08\u0e32\u0e01\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19\u0e04\u0e37\u0e2d<\/p>\n\n\n\n<p>1.\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48 \u0e40\u0e01\u0e47\u0e1a\u0e44\u0e02\u0e48\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e1c\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e38\u0e08\u0e34\u0e41\u0e25\u0e49\u0e27\u0e43\u0e2a\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e21\u0e14\u0e25\u0e39\u0e01<\/p>\n\n\n\n<p>2.\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e2d\u0e07\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48 \u0e41\u0e15\u0e48\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21<strong>\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48<\/strong>\u0e08\u0e30\u0e21\u0e35\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e2a\u0e39\u0e07 \u0e08\u0e36\u0e07\u0e21\u0e31\u0e01\u0e08\u0e30\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e2d\u0e1e\u0e0a\u0e31\u0e48\u0e19\u0e41\u0e23\u0e01\u0e01\u0e31\u0e19\u0e40\u0e22\u0e2d\u0e30 (\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27 \u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e44\u0e02\u0e48\u0e44\u0e14\u0e49\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e22\u0e49\u0e32\u0e22\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e0b\u0e48\u0e2d\u0e21\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e01\u0e25\u0e31\u0e27\u0e27\u0e48\u0e32\u0e02\u0e2d\u0e07\u0e40\u0e2b\u0e25\u0e27\u0e17\u0e35\u0e48\u0e04\u0e49\u0e32\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e17\u0e48\u0e2d\u0e08\u0e30\u0e21\u0e32\u0e23\u0e1a\u0e01\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e31\u0e07\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19 \u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e08\u0e36\u0e07\u0e2b\u0e19\u0e35\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e35)<\/p>\n\n\n\n<h3>\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e25\u0e22\u0e21\u0e35\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e47\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e04\u0e23\u0e31\u0e1a<\/h3>\n\n\n\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e27\u0e25\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e08\u0e30\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e04\u0e37\u0e2d\u0e2a\u0e32\u0e21\u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e2b\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e47\u0e44\u0e1b\u0e09\u0e35\u0e14\u0e2a\u0e35\u0e15\u0e23\u0e27\u0e08\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e0b\u0e49\u0e33 \u0e2b\u0e32\u0e01<strong>\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48<\/strong>\u0e2b\u0e32\u0e22<strong>\u0e15\u0e31\u0e19<\/strong>\u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e30\u0e22\u0e38\u0e48\u0e07\u0e01\u0e31\u0e19\u0e15\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e09\u0e35\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e21\u0e35\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e35\u0e19\u0e23\u0e32\u0e04\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01<\/p>\n\n\n\n<p>\u0e2b\u0e32\u0e01\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e31\u0e19\u0e2a\u0e32\u0e21\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e25\u0e49\u0e27\u0e1c\u0e25\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e2b\u0e27\u0e31\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e0d\u0e40\u0e1b\u0e25\u0e48\u0e32 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e01\u0e47\u0e08\u0e30\u0e41\u0e02\u0e47\u0e07\u0e41\u0e23\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e21\u0e35\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e44\u0e02\u0e48 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1c\u0e19\u0e31\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e22\u0e49\u0e32\u0e22\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e04\u0e23\u0e31\u0e1a<\/p>\n\n<\/div><\/div>\n\n\n<p>\u0e17\u0e33\u0e19\u0e31\u0e14\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a<strong><a href=\"https:\/\/www.yinyangclinic.com\/eng\/fallopian-tube\/\" data-type=\"page\" data-id=\"172\">\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19<\/a><\/strong>\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0<a href=\"tel:0947946006\">094-794-6006<\/a><\/p>\n\n\n\n<p>\u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e02\u0e49\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21 Facebook \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp;<a href=\"https:\/\/www.facebook.com\/chenyinyangclinic\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/www.facebook.com\/chenyinyangclinic<\/strong><\/a><\/p>\n\n\n\n<p>\u0e2b\u0e22\u0e34\u0e19\u0e2b\u0e22\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 999\/1-2 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e41\u0e02\u0e27\u0e07\u0e04\u0e25\u0e2d\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e40\u0e02\u0e15\u0e1a\u0e36\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e 10230<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19 \u0e04\u0e19\u0e44\u0e02\u0e49\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19\u0e2a\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e07\u0e1e\u0e36\u0e48\u0e07\u0e41\u0e08\u0e49\u0e07\u0e02\u0e48\u0e32\u0e27\u0e14 &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\" class=\"read-more button\" href=\"https:\/\/www.yinyangclinic.com\/eng\/%e0%b8%97%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%b3%e0%b9%84%e0%b8%82%e0%b9%88%e0%b8%95%e0%b8%b1%e0%b8%99-%e0%b9%82%e0%b8%ad%e0%b8%81%e0%b8%b2%e0%b8%aa%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%80%e0%b8%9b%e0%b8%b4\/#more-994\" aria-label=\"More on \u0e17\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e02\u0e48\u0e15\u0e31\u0e19 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\">Read More &gt;&gt;<\/a><\/p>\n","protected":false},"author":1,"featured_media":996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/994"}],"collection":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/comments?post=994"}],"version-history":[{"count":0,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media\/996"}],"wp:attachment":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media?parent=994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/categories?post=994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/tags?post=994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}