{"id":962,"date":"2022-01-10T14:29:13","date_gmt":"2022-01-10T07:29:13","guid":{"rendered":"https:\/\/www.yinyangclinic.com\/eng\/?p=962"},"modified":"2022-01-10T14:29:14","modified_gmt":"2022-01-10T07:29:14","slug":"%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%81%e0%b8%9c%e0%b8%99%e0%b8%88%e0%b8%b5%e0%b8%99%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b2-3","status":"publish","type":"post","link":"https:\/\/www.yinyangclinic.com\/eng\/%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%81%e0%b8%9c%e0%b8%99%e0%b8%88%e0%b8%b5%e0%b8%99%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b2-3\/","title":{"rendered":"\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01 PCOS"},"content":{"rendered":"<div class=\"gb-container gb-container-d1d6e6b2\"><div class=\"gb-inside-container\">\n\n<h1><strong>\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01 PCOS<\/strong><\/h1>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-881423ab\"><div class=\"gb-inside-container\">\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"630\" height=\"960\" src=\"https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2022\/01\/\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01-PCOS1.jpeg\" alt=\"\" class=\"wp-image-964\" srcset=\"https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2022\/01\/\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01-PCOS1.jpeg 630w, https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2022\/01\/\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01-PCOS1-197x300.jpeg 197w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><\/figure>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-2fb8d284\"><div class=\"gb-inside-container\">\n\n<blockquote class=\"wp-block-quote\"><p>\u0e22\u0e34\u0e19\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e04\u0e19\u0e44\u0e02\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e2d\u0e32\u0e22\u0e38 31 \u0e1b\u0e35 <strong><a href=\"https:\/\/www.yinyangclinic.com\/eng\/how-to-make-a-baby\/\" data-type=\"page\" data-id=\"140\">\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01<\/a><\/strong>\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30 PCOS (PolyCystic Ovary Syndrome) \u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e27\u0e30\u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e15\u0e01\u0e40\u0e23\u0e37\u0e49\u0e2d\u0e23\u0e31\u0e07<\/p><\/blockquote>\n\n\n\n<p>\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e38\u0e01 \u0e46 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e08\u0e30\u0e21\u0e35\u0e44\u0e02\u0e48\u0e42\u0e15\u0e40\u0e2a\u0e49\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2 \u0e0b\u0e21. \u0e40\u0e1e\u0e35\u0e22\u0e07 1\u0e43\u0e1a\u0e2b\u0e25\u0e38\u0e14\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e08\u0e32\u0e01\u0e23\u0e31\u0e07\u0e44\u0e02\u0e48 \u0e41\u0e25\u0e49\u0e27\u0e44\u0e1b\u0e1b\u0e0f\u0e34\u0e2a\u0e19\u0e18\u0e34\u0e01\u0e31\u0e1a\u0e2d\u0e2a\u0e38\u0e08\u0e34\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u00a0<img decoding=\"async\" alt=\"\ud83e\udd30\ud83c\udffc\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f930-1f3fc.svg\" style=\"width: 25px;\"><\/p>\n\n\n\n<p>\u0e41\u0e15\u0e48\u0e04\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 PCOS \u0e19\u0e31\u0e49\u0e19\u0e44\u0e02\u0e48\u0e21\u0e31\u0e01\u0e08\u0e30\u0e42\u0e15\u0e44\u0e21\u0e48\u0e16\u0e36\u0e07 2 \u0e0b\u0e21. \u0e42\u0e14\u0e22\u0e21\u0e32\u0e01\u0e21\u0e31\u0e01\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 1 \u0e0b\u0e21. \u0e41\u0e15\u0e48\u0e08\u0e30\u0e21\u0e35\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e1a \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e21\u0e35\u0e40\u0e22\u0e2d\u0e30\u0e40\u0e1b\u0e47\u0e19 10 \u0e43\u0e1a\u0e43\u0e19\u0e23\u0e31\u0e07\u0e44\u0e02\u0e48\u0e41\u0e15\u0e48\u0e25\u0e30\u0e02\u0e49\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e02\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e21\u0e48\u0e16\u0e36\u0e07 2 \u0e0b\u0e21.\u0e08\u0e36\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e44\u0e14\u0e49\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e1a<\/p>\n\n\n\n<p>\u0e42\u0e14\u0e22\u0e21\u0e32\u0e01\u0e42\u0e23\u0e04\u0e19\u0e35\u0e49\u0e21\u0e31\u0e01\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e23\u0e35\u0e22\u0e14 \u0e01\u0e32\u0e23\u0e19\u0e2d\u0e19\u0e14\u0e36\u0e01 \u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e19\u0e49\u0e2d\u0e22 \u0e01\u0e34\u0e19\u0e41\u0e1b\u0e49\u0e07 \u0e01\u0e34\u0e19\u0e2b\u0e27\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e02\u0e32\u0e14\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22 (\u0e19\u0e35\u0e48\u0e21\u0e31\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e35\u0e48\u0e41\u0e01!<img decoding=\"async\" alt=\"\ud83e\udd23\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f923.svg\" style=\"width: 25px;\">) \u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e19\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e08\u0e33\u0e19\u0e27\u0e19\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e41\u0e01\u0e27\u0e48\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e1a\u0e41\u0e25\u0e49\u0e27\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e27\u0e31\u0e22\u0e17\u0e33\u0e07\u0e32\u0e19\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07\u00a0<img decoding=\"async\" alt=\"\ud83d\udc69\ud83c\udffb\u200d\ud83d\udcbb\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f469-1f3fb-200d-1f4bb.svg\" style=\"width: 25px;\"><\/p>\n\n\n\n<p>\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32<strong>\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01<\/strong>\u0e08\u0e32\u0e01 <strong><a href=\"https:\/\/www.yinyangclinic.com\/eng\/pcos-%e0%b9%81%e0%b8%a5%e0%b8%b0%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%88%e0%b8%b3%e0%b9%80%e0%b8%94%e0%b8%b7%e0%b8%ad%e0%b8%99%e0%b9%84%e0%b8%a1%e0%b9%88%e0%b8%9b%e0%b8%81%e0%b8%95%e0%b8%b4%e0%b8%95\/\" data-type=\"page\" data-id=\"693\">PCOS<\/a><\/strong> \u0e19\u0e31\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e17\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e04\u0e23\u0e31\u0e1a \u0e43\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e02\u0e48\u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e42\u0e15 \u0e01\u0e47\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e08\u0e19\u0e21\u0e31\u0e19\u0e42\u0e15\u0e23\u0e32\u0e27 2 \u0e0b\u0e21. \u0e41\u0e25\u0e49\u0e27\u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e02\u0e48\u0e15\u0e01\u0e21\u0e32\u0e40\u0e08\u0e2d\u0e2d\u0e2a\u0e38\u0e08\u0e34\u0e44\u0e14\u0e49 \u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c<\/p>\n\n\n\n<p>\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e01\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e09\u0e35\u0e14 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e02\u0e48\u0e42\u0e15\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e09\u0e35\u0e14\u0e22\u0e32\u0e43\u0e2b\u0e49\u0e44\u0e02\u0e48\u0e15\u0e01 \u0e41\u0e25\u0e49\u0e27\u0e19\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e22\u0e38\u0e48\u0e07\u0e01\u0e31\u0e19\u0e40\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e09\u0e35\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d IUI \u0e40\u0e2a\u0e23\u0e34\u0e21<\/p>\n\n\n\n<p>\u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e37\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e23\u0e31\u0e07\u0e44\u0e02\u0e48\u0e21\u0e35\u0e44\u0e02\u0e48\u0e43\u0e1a\u0e40\u0e25\u0e47\u0e01 \u0e46 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e21\u0e32\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e1a\u0e32\u0e07\u0e17\u0e35\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e44\u0e02\u0e48\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e44\u0e02\u0e48\u0e42\u0e15\u0e2b\u0e25\u0e32\u0e22\u0e43\u0e1a\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e04\u0e19\u0e44\u0e02\u0e49\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e1a\u0e27\u0e21\u0e19\u0e49\u0e33 \u0e41\u0e19\u0e48\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e20\u0e32\u0e27\u0e30 OHSS (Ovarian Hyper Stimulate Syndrome) \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e08\u0e19\u0e44\u0e14\u0e49\u0e44\u0e02\u0e48\u0e40\u0e22\u0e2d\u0e30\u0e44\u0e1b \u0e0b\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e08\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e15\u0e48\u0e2d\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e17\u0e49\u0e2d\u0e07\u0e41\u0e1d\u0e14 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e19\u0e01\u0e32\u0e23\u0e04\u0e25\u0e2d\u0e14\u0e1a\u0e38\u0e15\u0e23\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e04\u0e38\u0e13\u0e2b\u0e21\u0e2d\u0e0a\u0e27\u0e19\u0e1e\u0e25\u0e34\u0e01\u0e27\u0e34\u0e01\u0e24\u0e15\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e44\u0e02\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e33\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27\u0e0b\u0e30\u0e40\u0e25\u0e22 (\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e04\u0e48\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e2b\u0e25\u0e31\u0e01\u0e1e\u0e31\u0e19\u0e2b\u0e21\u0e37\u0e48\u0e19 \u0e01\u0e47\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e41\u0e2a\u0e19\u0e41\u0e1a\u0e1a\u0e07\u0e07 \u0e46 ) \u0e41\u0e15\u0e48\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e23\u0e31\u0e07\u0e44\u0e02\u0e48\u0e01\u0e47\u0e44\u0e21\u0e48\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e01\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e09\u0e35\u0e14\u0e22\u0e31\u0e07\u0e44\u0e07\u0e44\u0e02\u0e48\u0e01\u0e47\u0e44\u0e21\u0e48\u0e42\u0e15\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a<\/p>\n\n\n\n<p><img decoding=\"async\" alt=\"\u262f\ufe0f\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/262f.svg\" style=\"width: 25px;\"> \u0e2a\u0e48\u0e27\u0e19\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e47\u0e08\u0e30\u0e21\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e02\u0e49\u0e41\u0e15\u0e48\u0e25\u0e30\u0e17\u0e48\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e31\u0e1a \u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e02\u0e32\u0e14\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e2d\u0e30\u0e44\u0e23 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e08\u0e30\u0e44\u0e1b\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e23\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e2a\u0e21\u0e14\u0e38\u0e25\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e31\u0e07\u0e44\u0e02\u0e48\u0e01\u0e47\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19\u0e15\u0e32\u0e21\u0e1b\u0e01\u0e15\u0e34 \u0e04\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e44\u0e02\u0e48\u0e42\u0e15 2 \u0e0b\u0e21.\u0e40\u0e1e\u0e35\u0e22\u0e07 1 \u0e43\u0e1a \u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e08\u0e35\u0e19\u0e08\u0e30\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e40\u0e01\u0e34\u0e19\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e01\u0e47\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e04\u0e23\u0e31\u0e1a\u00a0<img decoding=\"async\" alt=\"\u262f\ufe0f\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/262f.svg\" style=\"width: 25px;\"><\/p>\n\n\n\n<p>\u0e04\u0e19\u0e44\u0e02\u0e49 PCOS \u0e1a\u0e32\u0e07\u0e17\u0e48\u0e32\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e43\u0e19\u0e40\u0e25\u0e37\u0e2d\u0e14\u0e2a\u0e39\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30 Insulin resistance \u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e22\u0e48\u0e2d\u0e22\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e14\u0e35 \u0e2d\u0e31\u0e19\u0e19\u0e33\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1a\u0e32\u0e2b\u0e27\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e44\u0e14\u0e49 \u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e08\u0e36\u0e07\u0e19\u0e34\u0e22\u0e21\u0e43\u0e2b\u0e49\u0e22\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e40\u0e1a\u0e32\u0e2b\u0e27\u0e32\u0e19 (\u0e1e\u0e27\u0e01 Metformin \u0e2b\u0e23\u0e37\u0e2d Glucophage) \u0e01\u0e47\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e07\u0e07\u0e44\u0e1b \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e19\u0e49\u0e33\u0e15\u0e32\u0e25 \u0e1b\u0e23\u0e31\u0e1a\u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e32\u0e23\u0e04\u0e31\u0e14\u0e2b\u0e25\u0e31\u0e48\u0e07\u0e43\u0e19\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e22\u0e31\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e25\u0e14\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e25\u0e49\u0e27\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e14\u0e35\u0e15\u0e48\u0e2d PCOS \u0e01\u0e34\u0e19\u0e22\u0e32\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e40\u0e14\u0e34\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e49\u0e2d\u0e07\u0e2d\u0e37\u0e14 \u0e16\u0e48\u0e32\u0e22\u0e40\u0e2b\u0e25\u0e27 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e01\u0e15\u0e34 \u0e43\u0e2b\u0e49\u0e01\u0e34\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e34\u0e19\u0e02\u0e49\u0e32\u0e27\u0e44\u0e1b\u0e40\u0e25\u0e22\u0e08\u0e30\u0e25\u0e14\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a<\/p>\n\n\n\n<p>\u0e2b\u0e32\u0e01\u0e04\u0e19\u0e44\u0e02\u0e49 PCOS \u0e04\u0e19\u0e43\u0e14\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e21\u0e32\u0e01 \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e08\u0e30\u0e25\u0e14\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01 \u0e21\u0e35\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e16\u0e49\u0e32\u0e04\u0e38\u0e13\u0e25\u0e14\u0e44\u0e14\u0e49 10% \u0e02\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e2b\u0e19\u0e31\u0e01\u0e15\u0e31\u0e27 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e01\u0e15\u0e34\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 (\u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e19\u0e31\u0e01 80 \u0e01\u0e34\u0e42\u0e25 \u0e01\u0e47\u0e04\u0e27\u0e23\u0e25\u0e14\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e01 8 \u0e01\u0e34\u0e42\u0e25)<\/p>\n\n\n\n<p>\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e01\u0e47\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e23\u0e01 \u0e46 \u0e17\u0e35\u0e48\u0e2b\u0e21\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e02\u0e49\u0e08\u0e30\u0e17\u0e33 555555555\u00a0<img decoding=\"async\" alt=\"\ud83e\udd23\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f923.svg\" style=\"width: 25px;\">\u00a0\u0e17\u0e33\u0e44\u0e14\u0e49\u0e17\u0e33\u0e40\u0e2b\u0e2d\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22\u0e2d\u0e30\u0e44\u0e23 \u0e40\u0e14\u0e34\u0e19\u0e40\u0e23\u0e47\u0e27\u0e46\u0e2a\u0e31\u0e01\u0e04\u0e23\u0e36\u0e48\u0e07\u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c\u0e25\u0e30 3-4 \u0e27\u0e31\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e49\u0e27\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e2b\u0e19\u0e31\u0e01\u0e2d\u0e30\u0e44\u0e23\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e42\u0e22\u0e04\u0e30\u0e01\u0e47\u0e44\u0e14\u0e49\u00a0<img decoding=\"async\" alt=\"\ud83e\uddd8\ud83c\udffb\u200d\u2640\ufe0f\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f9d8-1f3fb-200d-2640-fe0f.svg\" style=\"width: 25px;\"><\/p>\n\n\n\n<p>\u0e43\u0e19\u0e40\u0e04\u0e2a\u0e19\u0e35\u0e49\u0e2b\u0e25\u0e31\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e44\u0e1b \u0e44\u0e02\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e42\u0e15\u0e41\u0e25\u0e30\u0e15\u0e01\u0e44\u0e14\u0e49\u0e40\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e02\u0e49\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e32\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d\u0e02\u0e36\u0e49\u0e19 \u0e08\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e44\u0e14\u0e49\u0e42\u0e14\u0e22\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e04\u0e23\u0e31\u0e1a \u0e22\u0e34\u0e19\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22<img decoding=\"async\" alt=\"\ud83c\udf89\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f389.svg\" style=\"width: 25px;\"><img decoding=\"async\" alt=\"\ud83c\udf89\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f389.svg\" style=\"width: 25px;\"><img decoding=\"async\" alt=\"\ud83c\udf89\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/13.1.0\/svg\/1f389.svg\" style=\"width: 25px;\"><\/p>\n\n<\/div><\/div>\n\n\n<p>\u0e17\u0e33\u0e19\u0e31\u0e14\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0<a href=\"tel:0947946006\"><strong>094-794-6006<\/strong><\/a><\/p>\n\n\n\n<p>\u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e02\u0e49\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21 Facebook \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp;<a href=\"https:\/\/www.facebook.com\/chenyinyangclinic\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/www.facebook.com\/chenyinyangclinic<\/strong><\/a><\/p>\n\n\n\n<p>\u0e2b\u0e22\u0e34\u0e19\u0e2b\u0e22\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 999\/1-2 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e41\u0e02\u0e27\u0e07\u0e04\u0e25\u0e2d\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e40\u0e02\u0e15\u0e1a\u0e36\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e 10230<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01 PCOS \u0e22\u0e34\u0e19\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e04\u0e19\u0e44\u0e02\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e2d\u0e32\u0e22\u0e38 31 \u0e1b\u0e35 \u0e21 &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01 PCOS\" class=\"read-more button\" href=\"https:\/\/www.yinyangclinic.com\/eng\/%e0%b9%81%e0%b8%9e%e0%b8%97%e0%b8%a2%e0%b9%8c%e0%b9%81%e0%b8%9c%e0%b8%99%e0%b8%88%e0%b8%b5%e0%b8%99%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b2-3\/#more-962\" aria-label=\"More on \u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01 PCOS\">Read More &gt;&gt;<\/a><\/p>\n","protected":false},"author":1,"featured_media":963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13,5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/962"}],"collection":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/comments?post=962"}],"version-history":[{"count":0,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media\/963"}],"wp:attachment":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media?parent=962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/categories?post=962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/tags?post=962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}