{"id":608,"date":"2021-12-14T15:11:56","date_gmt":"2021-12-14T08:11:56","guid":{"rendered":"https:\/\/www.yinyangclinic.com\/eng\/?p=608"},"modified":"2021-12-16T12:10:24","modified_gmt":"2021-12-16T05:10:24","slug":"%e0%b9%81%e0%b8%8a%e0%b8%a3%e0%b9%8c%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b2%e0%b8%a0%e0%b8%b2%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.yinyangclinic.com\/eng\/%e0%b9%81%e0%b8%8a%e0%b8%a3%e0%b9%8c%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b2%e0%b8%a0%e0%b8%b2%e0%b8%a7\/","title":{"rendered":"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\u0e32\u0e01\u0e08\u0e32\u0e01\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e1a\u0e38\u0e42\u0e1e\u0e23\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e34\u0e14\u0e17\u0e35\u0e48 \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15\u0e0b\u0e35\u0e2a\u0e15\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e0a\u0e49\u0e32"},"content":{"rendered":"<div class=\"gb-container gb-container-de1e0411\"><div class=\"gb-inside-container\">\n\n<h1><strong>\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e1a\u0e38\u0e42\u0e1e\u0e23\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e34\u0e14\u0e17\u0e35\u0e48 \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15\u0e0b\u0e35\u0e2a\u0e15\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e0a\u0e49\u0e32<\/strong><\/h1>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"2048\" height=\"1365\" src=\"https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2021\/12\/\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01.jpg\" alt=\"\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\" class=\"wp-image-609\" srcset=\"https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2021\/12\/\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01.jpg 2048w, https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2021\/12\/\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01-300x200.jpg 300w, https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2021\/12\/\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01-1024x683.jpg 1024w, https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2021\/12\/\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01-768x512.jpg 768w, https:\/\/www.yinyangclinic.com\/eng\/wp-content\/uploads\/2021\/12\/\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e1a\u0e38\u0e15\u0e23\u0e22\u0e32\u0e01-1536x1024.jpg 1536w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote\"><p><em>\u201c\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e02\u0e2d\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30<strong><a href=\"https:\/\/www.yinyangclinic.com\/eng\/how-to-make-a-baby\/\" data-type=\"page\" data-id=\"140\">\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01<\/a><\/strong>\u0e04\u0e30 \u0e14\u0e34\u0e09\u0e31\u0e19\u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e21\u0e35\u0e0b\u0e35\u0e2a\u0e17\u0e35\u0e48\u0e23\u0e31\u0e07\u0e44\u0e02\u0e48 \u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e32\u0e21\u0e35\u0e21\u0e35\u0e19\u0e33\u0e49\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e2d\u0e22 \u0e43\u0e19\u0e15\u0e2d\u0e19\u0e41\u0e23\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e22\u0e32\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e44\u0e02\u0e48 \u0e15\u0e48\u0e2d\u0e21\u0e32\u0e08\u0e36\u0e07\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e1c\u0e48\u0e32\u0e0b\u0e35\u0e2a\u0e2d\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e25\u0e2d\u0e07\u0e17\u0e33 IUI \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e1b\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e08\u0e36\u0e07\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32\u0e08\u0e30\u0e25\u0e2d\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e41\u0e1a\u0e1a\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e08\u0e35\u0e19\u0e14\u0e39 \u0e08\u0e36\u0e07\u0e21\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e22\u0e34\u0e19\u0e2b\u0e22\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 \u0e01\u0e34\u0e19\u0e22\u0e32\u0e08\u0e35\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 3 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e14\u0e49\u0e04\u0e30 \u0e15\u0e49\u0e2d\u0e07\u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e04\u0e38\u0e13\u0e2b\u0e21\u0e2d\u0e40\u0e0a\u0e19\u0e21\u0e32\u0e01\u0e46 \u0e19\u0e30\u0e04\u0e30\u201d<\/em><\/p><\/blockquote>\n\n\n\n<!--more-->\n\n\n\n<p>\u0e04\u0e39\u0e48\u0e2a\u0e32\u0e21\u0e35\u0e20\u0e23\u0e23\u0e22\u0e32\u0e2d\u0e32\u0e22\u0e38 32 \u0e17\u0e31\u0e49\u0e07\u0e04\u0e39\u0e48 \u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e40\u0e1e\u0e35\u0e22\u0e1a\u0e1e\u0e23\u0e49\u0e2d\u0e21<img decoding=\"async\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/12.0.0-1\/svg\/1f602.svg\" alt=\"\ud83d\ude02\" style=\"width: 15px;\"> \u0e1d\u0e48\u0e32\u0e22\u0e2b\u0e0d\u0e34\u0e07\u0e21\u0e35\u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15\u0e0b\u0e35\u0e2a\u0e15\u0e4c\u0e41\u0e25\u0e49\u0e27\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e2d\u0e2d\u0e01 \u0e40\u0e04\u0e22\u0e01\u0e34\u0e19\u0e22\u0e32\u0e01\u0e23\u0e30\u0e15\u0e38\u0e49\u0e19\u0e44\u0e02\u0e48\u0e41\u0e25\u0e49\u0e27\u0e25\u0e2d\u0e07\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e15\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e16\u0e36\u0e07 4 \u0e04\u0e23\u0e31\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e25\u0e2d\u0e07\u0e09\u0e35\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d IUI \u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e21\u0e35\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e0b\u0e36\u0e48\u0e07\u0e2d\u0e32\u0e08\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e0b\u0e35\u0e2a\u0e15\u0e4c\u0e41\u0e25\u0e49\u0e27\u0e01\u0e23\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e23\u0e31\u0e07\u0e44\u0e02\u0e48 (\u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u0e16\u0e49\u0e32\u0e0b\u0e35\u0e2a\u0e15\u0e4c\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e25\u0e2d\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e14\u0e49\u0e27\u0e22\u0e22\u0e32\u0e41\u0e17\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e23\u0e31\u0e1a)<\/p>\n\n\n\n<p>\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e41\u0e25\u0e49\u0e27\u0e2b\u0e25\u0e31\u0e07\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e0b\u0e35\u0e2a\u0e15\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19 1 \u0e1b\u0e35\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e2d\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e2a\u0e39\u0e07\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21 \u0e41\u0e15\u0e48\u0e15\u0e34\u0e14\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e1d\u0e48\u0e32\u0e22\u0e0a\u0e32\u0e22\u0e19\u0e31\u0e49\u0e19\u0e19\u0e49\u0e2d\u0e22 \u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07 5.2 \u0e25\u0e49\u0e32\u0e19\u0e15\u0e31\u0e27\/\u0e21\u0e34\u0e25\u0e25\u0e34\u0e25\u0e34\u0e15\u0e23\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 <img decoding=\"async\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/12.0.0-1\/svg\/1f631.svg\" alt=\"\ud83d\ude31\" style=\"width: 15px;\"> (\u0e04\u0e27\u0e23\u0e21\u0e35\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 15 \u0e25\u0e49\u0e32\u0e19\u0e15\u0e31\u0e27) \u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e0a\u0e49\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07 19% <img decoding=\"async\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/12.0.0-1\/svg\/1f922.svg\" alt=\"\ud83e\udd22\" style=\"width: 15px;\"> (\u0e04\u0e27\u0e23\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 32%) \u0e08\u0e36\u0e07\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e15\u0e48\u0e33 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e04\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e14\u0e47\u0e01\u0e2b\u0e25\u0e2d\u0e14\u0e41\u0e01\u0e49\u0e27 IVF \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/p>\n\n\n\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e31\u0e19\u0e44\u0e1b \u0e1c\u0e21\u0e43\u0e2b\u0e49\u0e27\u0e31\u0e14\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e17\u0e38\u0e01\u0e40\u0e0a\u0e49\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e14\u0e39\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e2b\u0e25\u0e31\u0e07\u0e44\u0e02\u0e48\u0e15\u0e01\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e21\u0e48\u0e14\u0e35 \u0e2a\u0e39\u0e07\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e31\u0e19\u0e01\u0e47\u0e15\u0e01\u0e25\u0e07\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e2a\u0e14\u0e07\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e42\u0e1b\u0e23\u0e40\u0e08\u0e2a\u0e40\u0e15\u0e2d\u0e42\u0e23\u0e19\u0e15\u0e48\u0e33 \u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e43\u0e2b\u0e49\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e40\u0e01\u0e32\u0e30\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e14\u0e35 \u0e42\u0e15\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e08\u0e36\u0e07\u0e43\u0e0a\u0e49\u0e22\u0e32\u0e08\u0e35\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49 (\u0e2e\u0e2d\u0e23\u0e4c\u0e42\u0e21\u0e19\u0e19\u0e35\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e19\u0e31\u0e07\u0e2b\u0e19\u0e32\u0e2a\u0e27\u0e22 \u0e2a\u0e32\u0e23\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e44\u0e1b\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e15\u0e31\u0e27\u0e2d\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e14\u0e35 \u0e25\u0e14\u0e01\u0e32\u0e23\u0e1a\u0e35\u0e1a\u0e15\u0e31\u0e27\u0e02\u0e2d\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e41\u0e17\u0e49\u0e07\u0e04\u0e38\u0e01\u0e04\u0e32\u0e21\u0e44\u0e14\u0e49)<\/p>\n\n\n\n<p>\u0e1d\u0e48\u0e32\u0e22\u0e0a\u0e32\u0e22\u0e2a\u0e39\u0e1a\u0e1a\u0e38\u0e2b\u0e23\u0e35\u0e48\u0e41\u0e25\u0e30\u0e40\u0e25\u0e34\u0e01\u0e21\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e41\u0e25\u0e49\u0e27\u0e0b\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e04\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e25\u0e34\u0e01\u0e44\u0e14\u0e49 \u0e21\u0e31\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e2a\u0e32\u0e21\u0e35\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e04\u0e27\u0e23\u0e40\u0e2d\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a <img decoding=\"async\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/12.0.0-1\/svg\/1f923.svg\" alt=\"\ud83e\udd23\" style=\"width: 16px;\"> \u0e2b\u0e25\u0e31\u0e07\u0e21\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e47\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e17\u0e31\u0e49\u0e07\u0e22\u0e32\u0e08\u0e35\u0e19\u0e41\u0e25\u0e30\u0e1d\u0e31\u0e07\u0e40\u0e02\u0e47\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e15\u0e32\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e22\u0e34\u0e19\u0e14\u0e35\u0e14\u0e49\u0e27\u0e22\u0e04\u0e23\u0e31\u0e1a <img decoding=\"async\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/12.0.0-1\/svg\/1f389.svg\" alt=\"\ud83c\udf89\" style=\"width: 15px;\"><img decoding=\"async\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/12.0.0-1\/svg\/1f389.svg\" alt=\"\ud83c\udf89\" style=\"width: 15px;\"><img decoding=\"async\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/12.0.0-1\/svg\/1f389.svg\" alt=\"\ud83c\udf89\" style=\"width: 15px;\"><\/p>\n\n\n\n<p>\u0e2b\u0e25\u0e31\u0e07\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e0b\u0e35\u0e2a\u0e15\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19 1 \u0e1b\u0e35\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e17\u0e2d\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e08\u0e30\u0e25\u0e14\u0e44\u0e1b\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e36\u0e48\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e41\u0e1a\u0e1a\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e0a\u0e30\u0e25\u0e48\u0e32\u0e43\u0e08\u0e19\u0e32\u0e19\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e2b\u0e32\u0e01\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e41\u0e25\u0e49\u0e27\u0e44\u0e21\u0e48\u0e15\u0e31\u0e49\u0e07\u0e04\u0e23\u0e23\u0e20\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e35\u0e1a\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e41\u0e1e\u0e17\u0e22\u0e4c<\/p>\n\n\n\n<p>\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-a7c29c2b\"><div class=\"gb-inside-container\">\n\n<p>\u0e17\u0e33\u0e19\u0e31\u0e14\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp;<a href=\"tel:0947946006\">094-794-6006<\/a><\/p>\n\n\n\n<p>\u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e02\u0e49\u0e32\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e0a\u0e21 Facebook \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48&nbsp;<a href=\"https:\/\/www.facebook.com\/chenyinyangclinic\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>https:\/\/www.facebook.com\/chenyinyangclinic<\/strong><\/a><\/p>\n\n\n\n<p>\u0e2b\u0e22\u0e34\u0e19\u0e2b\u0e22\u0e32\u0e07\u0e04\u0e25\u0e34\u0e19\u0e34\u0e01 999\/1-2 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32-\u0e23\u0e32\u0e21\u0e2d\u0e34\u0e19\u0e17\u0e23\u0e32 \u0e41\u0e02\u0e27\u0e07\u0e04\u0e25\u0e2d\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e40\u0e02\u0e15\u0e1a\u0e36\u0e07\u0e01\u0e38\u0e48\u0e21 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e 10230<\/p>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\u0e08\u0e32\u0e01\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e1a\u0e38\u0e42\u0e1e\u0e23\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e34\u0e14\u0e17\u0e35\u0e48 \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15\u0e0b\u0e35\u0e2a\u0e15\u0e4c \u0e44\u0e02\u0e48 &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\u0e32\u0e01\u0e08\u0e32\u0e01\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e1a\u0e38\u0e42\u0e1e\u0e23\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e34\u0e14\u0e17\u0e35\u0e48 \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15\u0e0b\u0e35\u0e2a\u0e15\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e0a\u0e49\u0e32\" class=\"read-more button\" href=\"https:\/\/www.yinyangclinic.com\/eng\/%e0%b9%81%e0%b8%8a%e0%b8%a3%e0%b9%8c%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%aa%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%93%e0%b9%8c%e0%b8%a3%e0%b8%b1%e0%b8%81%e0%b8%a9%e0%b8%b2%e0%b8%a0%e0%b8%b2%e0%b8%a7\/#more-608\" aria-label=\"More on \u0e41\u0e0a\u0e23\u0e4c\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e32\u0e20\u0e32\u0e27\u0e30\u0e21\u0e35\u0e25\u0e39\u0e01\u0e22\u0e32\u0e01\u0e32\u0e01\u0e08\u0e32\u0e01\u0e40\u0e22\u0e37\u0e48\u0e2d\u0e1a\u0e38\u0e42\u0e1e\u0e23\u0e07\u0e21\u0e14\u0e25\u0e39\u0e01\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1c\u0e34\u0e14\u0e17\u0e35\u0e48 \u0e0a\u0e47\u0e2d\u0e04\u0e42\u0e01\u0e41\u0e25\u0e15\u0e0b\u0e35\u0e2a\u0e15\u0e4c \u0e44\u0e02\u0e48\u0e44\u0e21\u0e48\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e19\u0e49\u0e33\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27\u0e0a\u0e49\u0e32\">Read More &gt;&gt;<\/a><\/p>\n","protected":false},"author":1,"featured_media":609,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,9,10],"tags":[],"_links":{"self":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/608"}],"collection":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/comments?post=608"}],"version-history":[{"count":0,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/posts\/608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media\/609"}],"wp:attachment":[{"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/media?parent=608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/categories?post=608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yinyangclinic.com\/eng\/wp-json\/wp\/v2\/tags?post=608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}